{"id":651,"date":"2022-10-07T07:06:24","date_gmt":"2022-10-07T07:06:24","guid":{"rendered":"https:\/\/demo.creativethemes.com\/elementor\/renovation\/?page_id=651"},"modified":"2026-05-08T19:42:42","modified_gmt":"2026-05-08T17:42:42","slug":"about-company","status":"publish","type":"page","link":"https:\/\/stp-extrusion.com\/de\/about-company\/","title":{"rendered":"\u00dcber uns"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"651\" class=\"elementor elementor-651\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a061cba e-flex e-con-boxed e-con e-parent\" data-id=\"a061cba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e0deba elementor-widget elementor-widget-spacer\" data-id=\"8e0deba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edb12ec elementor-widget elementor-widget-heading\" data-id=\"edb12ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00dcber uns <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca809fd elementor-widget elementor-widget-spacer\" data-id=\"ca809fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-515dee6 e-flex e-con-boxed e-con e-parent\" data-id=\"515dee6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d8ea41 elementor-widget elementor-widget-timeline-widget-addon\" data-id=\"4d8ea41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"timeline-widget-addon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- ========= Timeline Widget Addon For Elementor 1.6.24 ========= -->\n<div id=\"twae-wrapper-4d8ea41\" class=\"twae-vertical twae-wrapper  twae-both-sided\">   \n    <div class=\"twae-start\"><\/div>    \n    <div id=\"twea-timeline-4d8ea41\" class=\"twae-timeline\" ><!-- Start of Story Repeater Content --><div id=\"story-59b8088\" class=\"twae-story twae-repeater-item twae-story-right twae-story-no-icon\"><!-- Story Label --><div class=\"twae-labels\"><div class=\"twae-label-big\">Unsere Geschichte beginnt<\/div><\/div><!-- Story Icon --><div class=\"twae-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-eye\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M572.52 241.4C518.29 135.59 410.93 64 288 64S57.68 135.64 3.48 241.41a32.35 32.35 0 0 0 0 29.19C57.71 376.41 165.07 448 288 448s230.32-71.64 284.52-177.41a32.35 32.35 0 0 0 0-29.19zM288 400a144 144 0 1 1 144-144 143.93 143.93 0 0 1-144 144zm0-240a95.31 95.31 0 0 0-25.31 3.79 47.85 47.85 0 0 1-66.9 66.9A95.78 95.78 0 1 0 288 160z\"><\/path><\/svg><\/div><!-- Story Arrow --><div class=\"twae-arrow\"><\/div><!-- Start of Story Content --><div class=\"twae-content\"><!-- Story Title --><div class=\"twae-title\">Tatai H\u00e1ziipari Genossenschaft <br> <span style=\"font-family: MinionPro;font-size: 9pt;font-style: var(--theme-font-style, inherit);font-weight: 400;letter-spacing: var(--theme-letter-spacing);text-align: inherit;text-transform: var(--theme-text-transform);text-decoration: var(--theme-text-decoration)\"><br><\/span><\/div><!-- Story Description --><div class=\"twae-description\"><blockquote><div dir=\"ltr\"><div><div><p>1952 Die Kunststoffabteilung der Tatai H\u00e1ziipari Kooperative ist ein Pionier in der innovativen und hochwertigen Kunststofffertigung geworden. Durch die Kombination von fortschrittlichen Technologien mit handwerklichem K\u00f6nnen bietet sie eine breite Palette von Produkten, von Haushaltsgegenst\u00e4nden bis hin zu Industriekomponenten, die auf die vielf\u00e4ltigen Bed\u00fcrfnisse der Kunden zugeschnitten sind.\u00a0<\/p><\/div><\/div><\/div><\/blockquote><\/div><\/div><\/div><!-- Start of Story Repeater Content --><div id=\"story-6d15c58\" class=\"twae-story twae-repeater-item twae-story-left twae-story-no-icon\"><!-- Story Label --><div class=\"twae-labels\"><div class=\"twae-label-big\">Die Genossenschaft verkauft das Extruderwerk.<\/div><\/div><!-- Story Icon --><div class=\"twae-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-eye\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M572.52 241.4C518.29 135.59 410.93 64 288 64S57.68 135.64 3.48 241.41a32.35 32.35 0 0 0 0 29.19C57.71 376.41 165.07 448 288 448s230.32-71.64 284.52-177.41a32.35 32.35 0 0 0 0-29.19zM288 400a144 144 0 1 1 144-144 143.93 143.93 0 0 1-144 144zm0-240a95.31 95.31 0 0 0-25.31 3.79 47.85 47.85 0 0 1-66.9 66.9A95.78 95.78 0 1 0 288 160z\"><\/path><\/svg><\/div><!-- Story Arrow --><div class=\"twae-arrow\"><\/div><!-- Start of Story Content --><div class=\"twae-content\"><!-- Story Title --><div class=\"twae-title\">Mipol\u00e1n Ltd.<\/div><!-- Story Description --><div class=\"twae-description\"><blockquote><div dir=\"ltr\"><div class=\"yiv7930158910\"><div class=\"yiv7930158910\"><p class=\"yiv7930158910\">Unser Unternehmen, <a href=\"http:\/\/www.mipolan.hu\">Mipol\u00e1n<\/a> Ltd. wurde 1990 auf Initiative von Zolt\u00e1n Csel\u00e9des gegr\u00fcndet, der sein Unternehmen mit der Produktion von Elektroisolierungen und Gartenschl\u00e4uchen begann. Im Laufe der Jahre wurden mehrere andere Unternehmen integriert, bis im Jahr 2023 die ST Plastics sro gegr\u00fcndet wurde. Durch innovative und technisch hochwertige Produkte wurde das Unternehmen in Ungarn, der Slowakei und den angrenzenden L\u00e4ndern wie Kroatien, der Tschechischen Republik, Rum\u00e4nien und Polen bekannt. Im Jahr 2024 konnten wir auch auf den westeurop\u00e4ischen M\u00e4rkten Erfolge erzielen. Wir gewannen unsere ersten franz\u00f6sischen, niederl\u00e4ndischen und deutschen Partner.<\/p><\/div><\/div><\/div><\/blockquote><\/div><\/div><\/div><!-- Start of Story Repeater Content --><div id=\"story-96b24f0\" class=\"twae-story twae-repeater-item twae-story-right twae-story-no-icon\"><!-- Story Label --><div class=\"twae-labels\"><div class=\"twae-label-big\">Grundwerte und Ziele<\/div><\/div><!-- Story Icon --><div class=\"twae-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-lightbulb\" viewbox=\"0 0 352 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M96.06 454.35c.01 6.29 1.87 12.45 5.36 17.69l17.09 25.69a31.99 31.99 0 0 0 26.64 14.28h61.71a31.99 31.99 0 0 0 26.64-14.28l17.09-25.69a31.989 31.989 0 0 0 5.36-17.69l.04-38.35H96.01l.05 38.35zM0 176c0 44.37 16.45 84.85 43.56 115.78 16.52 18.85 42.36 58.23 52.21 91.45.04.26.07.52.11.78h160.24c.04-.26.07-.51.11-.78 9.85-33.22 35.69-72.6 52.21-91.45C335.55 260.85 352 220.37 352 176 352 78.61 272.91-.3 175.45 0 73.44.31 0 82.97 0 176zm176-80c-44.11 0-80 35.89-80 80 0 8.84-7.16 16-16 16s-16-7.16-16-16c0-61.76 50.24-112 112-112 8.84 0 16 7.16 16 16s-7.16 16-16 16z\"><\/path><\/svg><\/div><!-- Story Arrow --><div class=\"twae-arrow\"><\/div><!-- Start of Story Content --><div class=\"twae-content\"><!-- Story Title --><div class=\"twae-title\">ST-Kunststoffe<\/div><!-- Story Description --><div class=\"twae-description\"><blockquote><div dir=\"ltr\"><div class=\"yiv7930158910\"><div class=\"yiv7930158910\"><p class=\"yiv7930158910\">Seit der Gr\u00fcndung von Mipol\u00e1n streben wir nach Innovation und suchen nach individuellen L\u00f6sungen, indem wir uns zum Ziel setzen, unseren Gesch\u00e4ftspartnern kontinuierlich Wert und Vorteile durch st\u00e4ndig verbesserte Qualit\u00e4t, wettbewerbsf\u00e4hige Preise und kreative Ans\u00e4tze zu bieten. Als ST Plastics GmbH sind wir verpflichtet, die bisherigen Werte zu bewahren und weiterzuentwickeln.<\/p><\/div><\/div><\/div><\/blockquote><\/div><\/div><\/div><!-- Start of Story Repeater Content --><div id=\"story-4e53c70\" class=\"twae-story twae-repeater-item twae-story-left twae-story-no-icon\"><!-- Story Label --><div class=\"twae-labels\"><div class=\"twae-label-big\">Unsere St\u00e4rken<\/div><\/div><!-- Story Icon --><div class=\"twae-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chart-line\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M496 384H64V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16zM464 96H345.94c-21.38 0-32.09 25.85-16.97 40.97l32.4 32.4L288 242.75l-73.37-73.37c-12.5-12.5-32.76-12.5-45.25 0l-68.69 68.69c-6.25 6.25-6.25 16.38 0 22.63l22.62 22.62c6.25 6.25 16.38 6.25 22.63 0L192 237.25l73.37 73.37c12.5 12.5 32.76 12.5 45.25 0l96-96 32.4 32.4c15.12 15.12 40.97 4.41 40.97-16.97V112c.01-8.84-7.15-16-15.99-16z\"><\/path><\/svg><\/div><!-- Story Arrow --><div class=\"twae-arrow\"><\/div><!-- Start of Story Content --><div class=\"twae-content\"><!-- Story Title --><div class=\"twae-title\">Innovative F\u00fchrung<\/div><!-- Story Description --><div class=\"twae-description\"><blockquote><div dir=\"ltr\"><div class=\"yiv7930158910\"><div class=\"yiv7930158910\"><p class=\"yiv7930158910\">Durch unsere herausragenden Innovationen und Zuverl\u00e4ssigkeit, ST Plastics<span style=\"color: #000000;font-size: medium;text-align: start;font-family: inherit;font-style: inherit;letter-spacing: var(--theme-letter-spacing);text-transform: var(--theme-text-transform);text-decoration: var(--theme-text-decoration)\">\u2122<\/span><span style=\"font-family: inherit;font-size: inherit;font-style: inherit;text-align: var(--tw-cbx-text-align-alternate);letter-spacing: var(--theme-letter-spacing);text-transform: var(--theme-text-transform);text-decoration: var(--theme-text-decoration)\">\u00a0sichert langfristige Wettbewerbsvorteile. Durch die Kombination unserer Expertise in den Bereichen Automobilindustrie, Elektronik, Elektrotechnik, Bauwesen, Kunststoffindustrie, Lebensmittelindustrie und Medizinelektronik bieten wir umfassende L\u00f6sungen und Dienstleistungen an und st\u00e4rken damit unsere marktf\u00fchrende Position in Ungarn. Unser Unternehmen ist ein unabh\u00e4ngiger und vertrauensw\u00fcrdiger Partner.<\/span><\/p><\/div><\/div><\/div><\/blockquote><\/div><\/div><\/div><!-- Start of Story Repeater Content --><div id=\"story-dc54352\" class=\"twae-story twae-repeater-item twae-story-right twae-story-no-icon\"><!-- Story Label --><div class=\"twae-labels\"><div class=\"twae-label-big\">Unsere Vision<\/div><\/div><!-- Story Icon --><div class=\"twae-icon\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-globe\" viewbox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M336.5 160C322 70.7 287.8 8 248 8s-74 62.7-88.5 152h177zM152 256c0 22.2 1.2 43.5 3.3 64h185.3c2.1-20.5 3.3-41.8 3.3-64s-1.2-43.5-3.3-64H155.3c-2.1 20.5-3.3 41.8-3.3 64zm324.7-96c-28.6-67.9-86.5-120.4-158-141.6 24.4 33.8 41.2 84.7 50 141.6h108zM177.2 18.4C105.8 39.6 47.8 92.1 19.3 160h108c8.7-56.9 25.5-107.8 49.9-141.6zM487.4 192H372.7c2.1 21 3.3 42.5 3.3 64s-1.2 43-3.3 64h114.6c5.5-20.5 8.6-41.8 8.6-64s-3.1-43.5-8.5-64zM120 256c0-21.5 1.2-43 3.3-64H8.6C3.2 212.5 0 233.8 0 256s3.2 43.5 8.6 64h114.6c-2-21-3.2-42.5-3.2-64zm39.5 96c14.5 89.3 48.7 152 88.5 152s74-62.7 88.5-152h-177zm159.3 141.6c71.4-21.2 129.4-73.7 158-141.6h-108c-8.8 56.9-25.6 107.8-50 141.6zM19.3 352c28.6 67.9 86.5 120.4 158 141.6-24.4-33.8-41.2-84.7-50-141.6h-108z\"><\/path><\/svg><\/div><!-- Story Arrow --><div class=\"twae-arrow\"><\/div><!-- Start of Story Content --><div class=\"twae-content\"><!-- Story Title --><div class=\"twae-title\">Globalisierung<\/div><!-- Story Description --><div class=\"twae-description\"><blockquote><div dir=\"ltr\"><div class=\"yiv7930158910\"><div class=\"yiv7930158910\"><p class=\"yiv7930158910\">ST-Kunststoffe<span style=\"color: #000000;font-size: medium;font-family: inherit;font-style: inherit;text-align: var(--tw-cbx-text-align);letter-spacing: var(--theme-letter-spacing);text-transform: var(--theme-text-transform);text-decoration: var(--theme-text-decoration)\">\u2122<\/span><span style=\"font-family: inherit;font-size: inherit;font-style: inherit;text-align: var(--tw-cbx-text-align);letter-spacing: var(--theme-letter-spacing);text-transform: var(--theme-text-transform);text-decoration: var(--theme-text-decoration)\">, ein europaweit t\u00e4tiges Unternehmen, das als Familienbetrieb begonnen hat und sich nun auf internationalem Parkett behauptet, verfolgt die Diversifizierung seiner Gesch\u00e4ftsfelder und die Expansion \u00fcber L\u00e4ndergrenzen hinweg. Diese Strategie sichert unsere Stabilit\u00e4t und tr\u00e4gt zur Steigerung unseres wirtschaftlichen Erfolgs bei.<\/span><\/p><\/div><\/div><\/div><\/blockquote><\/div><\/div><\/div><\/div>\n    <div class=\"twae-end\"><\/div>\n    <\/div><style type=\"text\/css\">@media (max-width: 1024px){ .twae-wrapper{--tw-ybx-size: 80px !important;}}@media (max-width: 767px){ .twae-wrapper{--tw-ybx-size: 80px !important}}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb387c6 elementor-widget elementor-widget-text-editor\" data-id=\"cb387c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong>1. Ma\u00dfgeschneiderte L\u00f6sungen<\/strong><\/h4>\n<p>Das Expertenteam von ST Plastics<span style=\"caret-color: rgb(0, 0, 0); color: rgb(0, 0, 0); font-size: medium; text-align: var(--text-align); font-family: var(--theme-font-family); font-style: var(--theme-font-style, inherit); font-variant-caps: inherit; letter-spacing: var(--theme-letter-spacing); text-transform: var(--theme-text-transform); text-decoration: var(--theme-text-decoration);\">\u2122<\/span><span style=\"font-family: inherit; font-size: inherit; font-style: inherit; font-variant-caps: inherit; text-align: var(--text-align); letter-spacing: var(--theme-letter-spacing); text-transform: var(--theme-text-transform); text-decoration: var(--theme-text-decoration);\">&nbsp;arbeitet mit Ihnen zusammen, um Kunststoffprodukte nach Ihren individuellen Anforderungen zu entwerfen und herzustellen. Ob Sie L\u00f6sungen f\u00fcr spezifische industrielle Anwendungen oder kundenspezifische Projekte ben\u00f6tigen, wir sind bereit, die Herausforderung anzunehmen.<\/span><\/p>\n<p><strong>Unsere Vorteile:<\/strong><\/p>\n<ul>\n<li>Ma\u00dfgeschneiderte Designs<\/li>\n<li>Au\u00dfergew\u00f6hnliche Pr\u00e4zision und Langlebigkeit<\/li>\n<li>Breite Materialauswahl<\/li>\n<\/ul>\n<h4><strong>2. Standardisiertes Produktsortiment<\/strong><\/h4>\n<p>Unser Sortiment umfasst auch standardisierte Kunststoffrohre und -profile, die f\u00fcr verschiedene Industriezweige ideal sind. Unsere Produkte bieten die perfekte Balance zwischen Qualit\u00e4t und Kosteneffizienz.<\/p>\n<h4><strong>3. Nachhaltigkeit und Umweltverantwortung<\/strong><\/h4>\n<p class=\"translation-block\">Wir engagieren uns f\u00fcr eine umweltfreundliche Produktion. <strong>Mit modernen Technologien minimieren wir unseren \u00f6kologischen Fu\u00dfabdruck<\/strong>, w\u00e4hrend wir hohe Produktivit\u00e4t und Effizienz aufrechterhalten.<\/p>\n<p><strong>Unsere gr\u00fcnen Initiativen:<\/strong><\/p>\n<ul>\n<li>Verwendung von recycelten Materialien<\/li>\n<li>Abfallreduzierung im Produktionsprozess<\/li>\n<li>Energieeffiziente Technologien<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5796e21 e-flex e-con-boxed e-con e-parent\" data-id=\"5796e21\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38ad57f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"38ad57f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/stp-extrusion.com\/de\/#contact-main\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontakt<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-46322bc e-flex e-con-boxed e-con e-parent\" data-id=\"46322bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9afac40 elementor-widget elementor-widget-spacer\" data-id=\"9afac40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a6e9a0 e-flex e-con-boxed e-con e-parent\" data-id=\"6a6e9a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>About us The Beginning of Our StoryTatai H\u00e1ziipari cooperative 1952\u00a0The Tatai H\u00e1ziipari Cooperative&#8217;s plastic division has become a pioneer in innovative and high-quality plastic manufacturing. Combining advanced technologies with skilled craftsmanship, it offers a wide range of products, from household items to industrial components, tailored to meet diverse client needs.\u00a0 Cooperative sold the extrusion plantMipol\u00e1n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-651","page","type-page","status-publish","hentry"],"blocksy_meta":{"page_title_panel":"","has_hero_section":"disabled","46dd34ff6b5341647ab6a1afac859ff9":"","hero_section":"type-1","hero_elements":[{"id":"custom_title","enabled":true,"heading_tag":"h1","title":"Startseite"},{"id":"custom_description","enabled":true,"description_visibility":{"desktop":true,"tablet":true,"mobile":false}},{"id":"custom_meta","enabled":false,"meta_elements":[{"id":"author","enabled":true,"label":"By","has_author_avatar":"yes","avatar_size":25},{"id":"post_date","enabled":true,"label":"On","date_format_source":"default","date_format":"M j, Y"},{"id":"updated_date","enabled":false,"label":"On","date_format_source":"default","date_format":"M j, Y"},{"id":"categories","enabled":false,"label":"In","style":"simple"},{"id":"comments","enabled":true}],"page_meta_elements":{"joined":true,"articles_count":true,"comments":true}},{"id":"breadcrumbs","enabled":false}],"3c7d33fcdad3350225e5c2adffcdf951":"","hero_alignment1":"CT_CSS_SKIP_RULE","hero_margin":40,"hero_alignment2":"center","hero_vertical_alignment":"center","2f87530634270c6a49152d8da1467bbf":"","hero_structure":"narrow","61d660c549a251726f4cfaa9bccffa94":"","page_title_bg_type":"featured_image","custom_hero_background":{"attachment_id":null},"page_title_image_size":"full","parallax":{"desktop":false,"tablet":false,"mobile":false},"2f3f2a030c3acd69fd5aca129098cab2":"","hero_height":"250px","pageTitleFont":{"family":"Default","variation":"Default","size":"30px","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"pageTitleFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageMetaFont":{"family":"Default","variation":"n6","size":"12px","line-height":"1.3","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"uppercase","text-decoration":"CT_CSS_SKIP_RULE"},"pageMetaFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"page_meta_button_type_font_colors":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"page_meta_button_type_background_colors":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageExcerptFont":{"family":"Default","variation":"Default","size":"CT_CSS_SKIP_RULE","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"pageExcerptColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"breadcrumbsFont":{"family":"Default","variation":"Default","size":"CT_CSS_SKIP_RULE","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"breadcrumbsFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"initial":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageTitleOverlay":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"CT_CSS_SKIP_RULE"}}},"pageTitleBackground":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"var(--theme-palette-color-6)"}}},"pageTitlePadding":{"top":"50px","bottom":"50px","left":"auto","right":"auto","linked":true},"f65b90edb4c6044a60d833e3e5a5eb8b":"","page_structure_type":"default","0dd640da724c6b4e9e09465d1ce05799":"","content_style_source":"inherit","content_style":"wide","vertical_spacing_source":"custom","content_area_spacing":"none","background":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"CT_CSS_SKIP_RULE"}}},"content_background":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"var(--theme-palette-color-8)"}}},"content_boxed_shadow":{"inherit":false,"blur":18,"spread":-6,"v_offset":12,"h_offset":0,"inset":false,"enable":true,"color":{"color":"rgba(34, 56, 101, 0.04)"}},"content_boxed_border":{"width":1,"style":"none","color":{"color":"rgba(44,62,80,0.2)"}},"content_boxed_radius":{"top":"3px","bottom":"3px","left":"3px","right":"3px","linked":true},"boxed_content_spacing":{"desktop":{"top":"40px","bottom":"40px","left":"40px","right":"40px","linked":true},"tablet":{"top":"35px","bottom":"35px","left":"35px","right":"35px","linked":true},"mobile":{"top":"20px","bottom":"20px","left":"20px","right":"20px","linked":true}},"05c9511d640c53bd8e357c22ed03e0b4":"","disable_featured_image":"no","disable_share_box":"no","disable_header":"no","disable_footer":"no","styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Leaders in Extrusion | Plastic tubes and profiles<\/title>\n<meta name=\"description\" content=\"Learn more about STP Extrusion and our commitment to providing high-quality extrusion solutions. We offer a wide range of services.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stp-extrusion.com\/de\/about-company\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About\" \/>\n<meta property=\"og:description\" content=\"Learn more about STP Extrusion and our commitment to providing high-quality extrusion solutions. We offer a wide range of services.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stp-extrusion.com\/de\/about-company\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T17:42:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stp-extrusion.com\\\/about-company\\\/\",\"url\":\"https:\\\/\\\/stp-extrusion.com\\\/about-company\\\/\",\"name\":\"Leaders in Extrusion | Plastic tubes and profiles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stp-extrusion.com\\\/#website\"},\"datePublished\":\"2022-10-07T07:06:24+00:00\",\"dateModified\":\"2026-05-08T17:42:42+00:00\",\"description\":\"Learn more about STP Extrusion and our commitment to providing high-quality extrusion solutions. We offer a wide range of services.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stp-extrusion.com\\\/about-company\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stp-extrusion.com\\\/about-company\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stp-extrusion.com\\\/about-company\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stp-extrusion.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stp-extrusion.com\\\/#website\",\"url\":\"https:\\\/\\\/stp-extrusion.com\\\/\",\"name\":\"STP-extrusion.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/stp-extrusion.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stp-extrusion.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stp-extrusion.com\\\/#organization\",\"name\":\"ST Plastics\",\"url\":\"https:\\\/\\\/stp-extrusion.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stp-extrusion.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ST Plastics\"},\"image\":{\"@id\":\"https:\\\/\\\/stp-extrusion.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"F\u00fchrend in der Extrusion | Kunststoffrohre und -profile","description":"Erfahren Sie mehr \u00fcber STP Extrusion und unser Engagement, qualitativ hochwertige Extrusionsl\u00f6sungen anzubieten. Wir bieten eine breite Palette von Dienstleistungen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stp-extrusion.com\/de\/about-company\/","og_locale":"de_DE","og_type":"article","og_title":"About","og_description":"Learn more about STP Extrusion and our commitment to providing high-quality extrusion solutions. We offer a wide range of services.","og_url":"https:\/\/stp-extrusion.com\/de\/about-company\/","article_modified_time":"2026-05-08T17:42:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stp-extrusion.com\/about-company\/","url":"https:\/\/stp-extrusion.com\/about-company\/","name":"F\u00fchrend in der Extrusion | Kunststoffrohre und -profile","isPartOf":{"@id":"https:\/\/stp-extrusion.com\/#website"},"datePublished":"2022-10-07T07:06:24+00:00","dateModified":"2026-05-08T17:42:42+00:00","description":"Erfahren Sie mehr \u00fcber STP Extrusion und unser Engagement, qualitativ hochwertige Extrusionsl\u00f6sungen anzubieten. Wir bieten eine breite Palette von Dienstleistungen.","breadcrumb":{"@id":"https:\/\/stp-extrusion.com\/about-company\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stp-extrusion.com\/about-company\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stp-extrusion.com\/about-company\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stp-extrusion.com\/"},{"@type":"ListItem","position":2,"name":"About"}]},{"@type":"WebSite","@id":"https:\/\/stp-extrusion.com\/#website","url":"https:\/\/stp-extrusion.com\/","name":"STP-extrusion.com","description":"","publisher":{"@id":"https:\/\/stp-extrusion.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stp-extrusion.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/stp-extrusion.com\/#organization","name":"ST-Kunststoffe","url":"https:\/\/stp-extrusion.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stp-extrusion.com\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ST Plastics"},"image":{"@id":"https:\/\/stp-extrusion.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/stp-extrusion.com\/de\/wp-json\/wp\/v2\/pages\/651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stp-extrusion.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stp-extrusion.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stp-extrusion.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stp-extrusion.com\/de\/wp-json\/wp\/v2\/comments?post=651"}],"version-history":[{"count":72,"href":"https:\/\/stp-extrusion.com\/de\/wp-json\/wp\/v2\/pages\/651\/revisions"}],"predecessor-version":[{"id":3460,"href":"https:\/\/stp-extrusion.com\/de\/wp-json\/wp\/v2\/pages\/651\/revisions\/3460"}],"wp:attachment":[{"href":"https:\/\/stp-extrusion.com\/de\/wp-json\/wp\/v2\/media?parent=651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}